{"id":926,"date":"2024-08-27T23:03:40","date_gmt":"2024-08-28T02:03:40","guid":{"rendered":"https:\/\/msbmanager.us\/es\/?page_id=926"},"modified":"2024-08-27T23:11:46","modified_gmt":"2024-08-28T02:11:46","slug":"politicas-de-privacidad","status":"publish","type":"page","link":"https:\/\/msbmanager.us\/es\/politicas-de-privacidad\/","title":{"rendered":"Pol\u00edticas de Privacidad"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"926\" class=\"elementor elementor-926\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9eec25e elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"9eec25e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-02a81a8 jltma-glass-effect-no\" data-id=\"02a81a8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e3fdc2 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"8e3fdc2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MSB Manager, LLC. Pol\u00edticas de Privacidad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5861389 elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"5861389\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c705be jltma-glass-effect-no\" data-id=\"8c705be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad36eef jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"ad36eef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1. Consideraciones Iniciales\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8418734 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"8418734\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">MsB Manager, LLC. (\u201cMsB Manager\u201d o \u201cnosotros\u201d) toma la privacidad muy en serio. Por ello, en esta Pol\u00edtica de Privacidad (\u201cPol\u00edtica\u201d) explicamos c\u00f3mo utilizamos, almacenamos, compartimos y protegemos los datos personales recopilados durante el uso de nuestros servicios y soluciones (en conjunto, los \u201cServicios\u201d) y visitas a nuestros sitios web, blogs y redes sociales. Adem\u00e1s, describimos c\u00f3mo los titulares de datos pueden ejercer los derechos previstos en la legislaci\u00f3n aplicable. Los datos personales recopilados por nosotros dependen del contexto de sus interacciones con nuestros Servicios. En esta Pol\u00edtica, explicamos c\u00f3mo tratamos los datos de clientes de MsB Manager (\u201cClientes\u201d), de los consumidores de nuestros Clientes (\u201cConsumidores\u201d) y de los usuarios de nuestros sitios web, blogs y redes sociales (\u201cVisitantes\u201d) \u2013 en conjunto referidos como \u201cTitulares de Datos\u201d o \u201custed\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f74375b jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"f74375b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2. Clientes\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b2de23 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"6b2de23\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2.1 Informaci\u00f3n que Recopilamos\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afc26c6 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"afc26c6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cuando usted (a los efectos de esta secci\u00f3n, \u201cCliente y usuarios de la cuenta del Cliente\u201d) utiliza o interact\u00faa con los Servicios, recopilamos sus datos personales y\/o profesionales, que pueden dividirse en dos categor\u00edas:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-390c8bf jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"390c8bf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">(i) Datos proporcionados por usted:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9b612d elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"f9b612d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Datos de contacto profesional, como nombre, cargo, empresa, ubicaci\u00f3n, tel\u00e9fono y correo electr\u00f3nico;<\/li><li>Preferencias de marketing;<\/li><li>Credenciales de la cuenta, como direcci\u00f3n de correo electr\u00f3nico, ID de usuario y contrase\u00f1a;<\/li><li>Informaci\u00f3n de pago, como datos de tarjeta de cr\u00e9dito y bancarios, y direcci\u00f3n de facturaci\u00f3n;<\/li><li>Datos relacionados con soporte t\u00e9cnico y resoluci\u00f3n de problemas, incluidos datos de apertura de tickets y contenido de las comunicaciones con nosotros;<\/li><li>Datos financieros, como informaci\u00f3n relacionada con facturaci\u00f3n, ingresos, gastos y flujo de efectivo;<\/li><li>Datos de terceros, al usar nuestras plataformas y servicios, de acuerdo con los t\u00e9rminos de servicio contratados.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6713b34 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"6713b34\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">(ii) Datos recopilados autom\u00e1ticamente por nosotros:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84121a3 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"84121a3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Datos sobre los dispositivos usados para acceder a los Servicios, como direcci\u00f3n IP, sistema operativo, geolocalizaci\u00f3n e identificador del dispositivo;<\/li><li>Datos de registro, como direcci\u00f3n IP y actividades en los Servicios, incluida la fecha y la hora, p\u00e1ginas vistas y funcionalidades utilizadas;<\/li><li>Datos de navegaci\u00f3n y uso de los Servicios, incluido el rendimiento de los Servicios y m\u00e9tricas relacionadas con el env\u00edo de correos electr\u00f3nicos y otras comunicaciones.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-244ad38 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"244ad38\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2.2 C\u00f3mo Usamos Estos Datos\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e4c9bf elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"5e4c9bf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Usamos los datos recopilados o recibidos como resultado del uso de los Servicios para los siguientes prop\u00f3sitos:<\/p><ul><li>Cumplir nuestras obligaciones contractuales, incluidos la creaci\u00f3n y generaci\u00f3n de accesos, verificaci\u00f3n de identidad, cobro de montos adeudados y personalizaci\u00f3n de los servicios;<\/li><li>Notificar sobre cambios en nuestros productos y servicios;<\/li><li>Reforzar nuestros procedimientos de seguridad y protecci\u00f3n;<\/li><li>Realizar operaciones internas, como soporte, resoluci\u00f3n de problemas y an\u00e1lisis de datos;<\/li><li>Proporcionar informaci\u00f3n sobre otros servicios y\/o productos que ofrecemos y que son similares a los contratados;<\/li><li>Evaluar la efectividad de la publicidad y ofrecer publicidad relevante;<\/li><li>Gestionar riesgos y detectar, prevenir y\/o corregir fraudes o actividades ilegales;<\/li><li>Establecer, ejercer y defender derechos en procesos judiciales, administrativos o arbitrales;<\/li><li>Otros fines informados en el momento de la recopilaci\u00f3n o seg\u00fan autorizado por la ley.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fd9f6a jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"2fd9f6a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3. Consumidores\n\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-deae4f5 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"deae4f5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3.1 Datos de los Consumidores Recibidos de Nuestros Clientes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a988ff elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"0a988ff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol start=\"3\"><li>Cuando usted (referido en esta secci\u00f3n como \u201cconsumidores de nuestros clientes\u201d) utiliza los servicios de uno de nuestros clientes para hacer remesas de dinero, y nuestros clientes registran su informaci\u00f3n en nuestro software, recopilamos la informaci\u00f3n que ellos nos proporcionan. MsB Manager, LLC. no es responsable de las pr\u00e1cticas de privacidad o seguridad de sus clientes. Para entender c\u00f3mo sus datos son procesados por nuestros clientes o por las compa\u00f1\u00edas de remesas, consulte las pol\u00edticas de privacidad relevantes.<\/li><\/ol><ul><li>Datos de identificaci\u00f3n, como nombre, tel\u00e9fono, direcci\u00f3n, cargo profesional, n\u00famero de SSN\/ITIN, fecha de nacimiento;<\/li><li>Datos financieros, como ingresos, impuestos, comprobantes de salario y otros documentos relacionados;<\/li><li>Historial de remesas, como datos sobre transacciones anteriores realizadas por los clientes;<\/li><li>Datos de los beneficiarios como, nombre, clave PIX, informaci\u00f3n bancaria, CPF, etc.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b6c431 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"5b6c431\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3.2 C\u00f3mo Usamos Estos Datos\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4aec4a3 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"4aec4a3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Usamos los datos proporcionados por nuestros clientes como resultado del uso de los Servicios para los siguientes prop\u00f3sitos:<\/p><ul><li>Proporcionar y gestionar los servicios de software contratados por el cliente, incluidos la creaci\u00f3n y actualizaci\u00f3n de historiales de remesas financieras;<\/li><li>Desarrollar estrategias de marketing para nuestros clientes, permitiendo que ofrezcan publicidad relevante para usted;<\/li><li>Proporcionar informaci\u00f3n e informes para que el cliente pueda ofrecer un mejor soporte y atenci\u00f3n al consumidor;<\/li><li>Realizar an\u00e1lisis e informes internos para mejorar los servicios del cliente;<\/li><li>Gestionar riesgos y detectar, prevenir y\/o corregir fraudes o actividades ilegales.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c69e31a jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"c69e31a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4. Visitantes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e901930 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"e901930\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esta secci\u00f3n se aplica a los datos personales que recopilamos cuando usted (para los fines de esta secci\u00f3n, \u201cVisitantes\u201d) visita los sitios web, blogs y redes sociales de MsB Manager, LLC.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bbcc1e jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"7bbcc1e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4.1. Datos Recopilados por Nosotros\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-127b095 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"127b095\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">(i) Datos proporcionados por usted:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa3c4f8 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"fa3c4f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nuestros sitios web y blogs ofrecen varias formas de contacto. Usted puede proporcionar datos personales, por ejemplo, al expresar inter\u00e9s en obtener m\u00e1s informaci\u00f3n sobre nuestros productos y servicios, participar en encuestas, suscribirse a nuestro bolet\u00edn, descargar contenido informativo o contactarnos por otros medios. Estos datos incluyen:<\/p><ul><li>Datos de contacto profesional, como nombre, cargo, empresa, ubicaci\u00f3n, tel\u00e9fono y correo electr\u00f3nico;<\/li><li>\u00c1rea de actividad e inter\u00e9s;<\/li><li>Naturaleza de su comunicaci\u00f3n con nosotros;<\/li><li>Preferencias de marketing;<\/li><li>Cualquier informaci\u00f3n que desee compartir con nosotros.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45532b7 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"45532b7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">(ii) Datos recopilados autom\u00e1ticamente por nosotros:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f32f9a elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"7f32f9a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cuando usted usa nuestros sitios web, podemos recopilar y almacenar datos autom\u00e1ticamente. Estos datos incluyen:<\/p><ul><li>Datos sobre los dispositivos usados para acceder a los Servicios, como direcci\u00f3n IP, sistema operativo, informaci\u00f3n del navegador, geolocalizaci\u00f3n e identificadores \u00fanicos del dispositivo;<\/li><li>Datos de navegaci\u00f3n, es decir, c\u00f3mo usa e interact\u00faa con nuestros Servicios y materiales informativos;<\/li><li>Datos de contacto profesional, como nombre, cargo, empresa, ubicaci\u00f3n, tel\u00e9fono y correo electr\u00f3nico;<\/li><li>\u00c1rea de actividad e inter\u00e9s;<\/li><li>Naturaleza de su comunicaci\u00f3n con nosotros;<\/li><li>Preferencias de marketing;<\/li><li>Cualquier informaci\u00f3n que desee compartir con nosotros.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e7e76e jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"4e7e76e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4.2. C\u00f3mo Usamos Estos Datos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b860c91 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"b860c91\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Podemos utilizar los datos recopilados o recibidos como resultado del uso de nuestros sitios para los siguientes fines:<\/p><ul><li>Proporcionar, personalizar y mejorar nuestros sitios;<\/li><li>Reforzar procedimientos de seguridad y protecci\u00f3n;<\/li><li>Realizar operaciones internas, como soluci\u00f3n de problemas y an\u00e1lisis de datos;<\/li><li>Procesar transacciones y gestionar cuentas en l\u00ednea;<\/li><li>Enviar comunicaciones de marketing y recomendar productos o servicios, seg\u00fan sus preferencias;<\/li><li>Evaluar la efectividad de la publicidad y ofrecer publicidad relevante;<\/li><li>Gestionar riesgos y detectar, prevenir y\/o corregir fraudes o actividades ilegales.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-937d8cc jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"937d8cc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5. Compartici\u00f3n de Informaci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffbf2ba elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"ffbf2ba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol start=\"5\"><li>Podemos compartir los datos personales que recopilamos con terceros y socios comerciales para la prestaci\u00f3n e integraci\u00f3n de los Servicios. Esta compartici\u00f3n de datos se basa en los siguientes criterios y prop\u00f3sitos:<\/li><\/ol><ul><li><strong>Proveedores de Servicios Externos:<\/strong> Trabajamos con proveedores de servicios que nos ayudan a operar, ejecutar, mejorar, entender, personalizar, procesar pagos, proporcionar soporte y anunciar nuestros Servicios. Cuando compartimos datos con proveedores de servicios externos, ellos est\u00e1n obligados a usar sus datos de acuerdo con nuestras instrucciones y t\u00e9rminos, o con su consentimiento, cuando sea aplicable.<\/li><li><strong>\u00d3rganos Reguladores y Autoridades Judiciales o Administrativas:<\/strong> Podemos compartir su informaci\u00f3n personal para proporcionar informaci\u00f3n solicitada por las autoridades competentes en relaci\u00f3n con un determinado Titular de Datos y las transacciones realizadas. Adem\u00e1s, podemos compartir sus datos personales con autoridades gubernamentales o entidades privadas para evitar fraudes y abusos, investigar violaciones de la ley o combatir sospechas de no conformidad con nuestras pol\u00edticas y contratos.<\/li><li><strong>Con Su Autorizaci\u00f3n:<\/strong> En otros casos no mencionados anteriormente, si pretendemos compartir sus datos personales e informaci\u00f3n, le enviaremos un aviso con informaci\u00f3n sobre la compartici\u00f3n y solicitaremos su consentimiento en relaci\u00f3n con el prop\u00f3sito espec\u00edfico de esa compartici\u00f3n.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-095948c jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"095948c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5.1. Proceso de Pago de Terceros\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-003d97e elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"003d97e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Actualmente, utilizamos procesadores de pagos de terceros para servicios de pago en l\u00ednea. Si desea hacer un pago a trav\u00e9s de los Servicios MsB Manager, su Informaci\u00f3n Personal puede ser recopilada directamente por estos procesadores, y no por nosotros, estando sujeta a la pol\u00edtica de privacidad de terceros. No tenemos control y no somos responsables por la recopilaci\u00f3n, uso y divulgaci\u00f3n de su Informaci\u00f3n Personal por terceros.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25c89a5 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"25c89a5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">6. Cookies y Tecnolog\u00edas de Seguimiento\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d838d3f elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"d838d3f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Podemos utilizar diferentes tecnolog\u00edas para recolectar y almacenar autom\u00e1ticamente datos sobre el uso de los Servicios. Estas tecnolog\u00edas pueden incluir cookies, p\u00edxeles, balizas web y SDKs. El uso de cookies para rastrear y almacenar informaci\u00f3n permitir\u00e1 que MsB Manager ofrezca un servicio m\u00e1s personalizado, de acuerdo con las caracter\u00edsticas e intereses de los usuarios, lo que permitir\u00e1 ofrecer contenido espec\u00edfico y mejorar su experiencia en Internet.<\/p><p><b>En general, las cookies se utilizan para:<\/b><\/p><ul><li>Proporcionar servicios diferenciados, recordando qui\u00e9n es el usuario y sus h\u00e1bitos de navegaci\u00f3n, adem\u00e1s de acceder a su informaci\u00f3n de registro en <a href=\"https:\/\/msbmanager.us\" target=\"_new\" rel=\"noopener\">https:\/\/msbmanager.us<\/a> o <a href=\"https:\/\/blog.msbmanager.us\" target=\"_new\" rel=\"noopener\">https:\/\/blog.msbmanager.us<\/a> (almacenada en nuestros servidores).<\/li><li>Monitorear el progreso de las promociones. Cuando una promoci\u00f3n organizada por nosotros utiliza cookies, la informaci\u00f3n registrada indica la puntuaci\u00f3n del usuario.<\/li><li>Medir ciertos patrones de navegaci\u00f3n, mapear \u00e1reas del sitio de MsB Manager visitadas por el usuario y sus h\u00e1bitos de visita. Usamos esta informaci\u00f3n para verificar la rutina de navegaci\u00f3n de nuestros usuarios y ofrecer contenido y\/o servicios m\u00e1s personalizados.<\/li><li>Facilitar y agilizar el llenado de formularios. La informaci\u00f3n contenida en las cookies de cada usuario puede ser utilizada para pre-rellenar los formularios de recolecci\u00f3n de datos existentes en Internet.<\/li><li>Anunciantes, socios y\/o patrocinadores de MsB Manager pueden utilizar sus propias cookies, que no est\u00e1n cubiertas por esta Pol\u00edtica. Sugerimos que el usuario consulte las pol\u00edticas de privacidad de esas empresas.<\/li><\/ul><p>El usuario tiene la opci\u00f3n de desactivar las cookies en la configuraci\u00f3n del navegador o cambiando las herramientas de programas antivirus. Sin embargo, esto puede alterar la forma en que interact\u00faa con nuestros u otros sitios y puede afectar o impedir el inicio de sesi\u00f3n en programas, sitios o foros de nuestras y otras redes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56687b5 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"56687b5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">7. Interacciones con Sitios Web de Terceros\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98ed842 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"98ed842\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>MsB Manager, LLC. tiene enlaces a otros sitios web en Internet. Sin embargo, no somos responsables de estos sitios web y su contenido. Adem\u00e1s, no compartimos, respaldamos, supervisamos, validamos ni aceptamos c\u00f3mo estos sitios web o herramientas de almacenamiento de contenido recopilan, procesan y transfieren su informaci\u00f3n personal y privada. Le recomendamos que consulte las pol\u00edticas de privacidad de estos sitios web para obtener informaci\u00f3n sobre el uso de su informaci\u00f3n personal por otros sitios web o herramientas.<\/p><p>Podemos registrar su acceso a sitios web de terceros con el prop\u00f3sito de medir su importancia para nuestros clientes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00c8bd0 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"00c8bd0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">8. Seguridad\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-285ec87 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"285ec87\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La informaci\u00f3n en la cuenta de MsB Manager, LLC. est\u00e1 protegida por contrase\u00f1a para que solo el usuario tenga acceso a su informaci\u00f3n personal. La contrase\u00f1a es confidencial y recomendamos que el usuario no la revele a nadie. MsB Manager, LLC. no solicitar\u00e1, bajo ninguna circunstancia, ya sea por correo electr\u00f3nico o tel\u00e9fono, la contrase\u00f1a personal del usuario. El usuario debe recordar cerrar sesi\u00f3n en su cuenta y cerrar la ventana del navegador al navegar por Internet.<\/p><p>Ninguna transmisi\u00f3n de datos a trav\u00e9s de Internet es 100% segura. Por lo tanto, aunque MsB Manager, LLC. hace todo lo posible por proteger su informaci\u00f3n personal, es imposible garantizar la seguridad total de toda la informaci\u00f3n proporcionada. La decisi\u00f3n de usar el servicio bajo estas condiciones es personal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff5447a jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"ff5447a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">9. Sus Derechos y Opciones\n\n\n\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-836e28a elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"836e28a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los titulares de datos personales tienen ciertos derechos respecto a sus datos y pueden ejercer estos derechos contact\u00e1ndonos en: <a rel=\"noopener\">support@msbmanager.us<\/a>.<\/p><p>Estos derechos incluyen:<\/p><ul><li>Confirmaci\u00f3n de la existencia de procesamiento de datos personales;<\/li><li>Acceso a los datos personales seg\u00fan la legislaci\u00f3n aplicable;<\/li><li>Correcci\u00f3n de datos incompletos, inexactos o desactualizados;<\/li><li>Portabilidad de datos;<\/li><li>Eliminaci\u00f3n de datos, cuando se procesen con base en el consentimiento del titular o cuando ya no sean necesarios, excesivos o no est\u00e9n en conformidad con la legislaci\u00f3n aplicable;<\/li><li>Solicitud de informaci\u00f3n sobre el compartimiento de datos. Tenga en cuenta que esta Pol\u00edtica describe el compartimiento de datos por MsB Manager, LLC. Para m\u00e1s informaci\u00f3n, cont\u00e1ctenos;<\/li><li>Retiro del consentimiento, si corresponde.<\/li><\/ul><p>Por razones de seguridad, atenderemos sus solicitudes solo si podemos verificar su identidad. Podemos solicitar datos o informaci\u00f3n adicional para validar su identidad y la autenticidad del titular de los datos.<\/p><p>Tenga en cuenta que, como se mencion\u00f3, MsB Manager tambi\u00e9n maneja datos de consumidores seg\u00fan el uso que nuestros clientes hagan de nuestros servicios. Si usted es un consumidor y desea ejercer sus derechos respecto a los datos personales gestionados por MsB Manager, comun\u00edquese con el cliente que est\u00e1 utilizando los servicios.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-168bb0d jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"168bb0d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">10. Ley de Privacidad del Consumidor de California\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-147a2b0 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"147a2b0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Ley de Privacidad del Consumidor de California (\u201cCCPA\u201d) otorga a los consumidores derechos espec\u00edficos en relaci\u00f3n con su Informaci\u00f3n Personal. Usted, como consumidor de nuestros clientes, tiene el derecho de solicitar que las empresas sujetas a la CCPA (que pueden incluir a nuestros clientes) divulguen cierta informaci\u00f3n sobre la recopilaci\u00f3n y uso de su Informaci\u00f3n Personal durante los \u00faltimos 12 meses. Adem\u00e1s, tiene el derecho de solicitar que estas empresas eliminen la Informaci\u00f3n Personal recopilada de usted (se aplican ciertas excepciones). Si una empresa vende Informaci\u00f3n Personal, usted tiene el derecho de optar por no participar en esa venta. Finalmente, una empresa no puede discriminarlo por ejercer un derecho bajo la CCPA.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5f9ed4 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"a5f9ed4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">11. Terminaci\u00f3n del Procesamiento<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b24b840 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"b24b840\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esta Pol\u00edtica de Privacidad es aplicable durante el per\u00edodo en que MsB Manager, LLC. almacene datos personales. Almacenamos y mantenemos su informaci\u00f3n: (i) por el tiempo requerido por la ley; (ii) hasta el t\u00e9rmino del procesamiento de datos personales, como se menciona a continuaci\u00f3n; o (iii) por el tiempo necesario para preservar el inter\u00e9s leg\u00edtimo de MsB Manager. Procesaremos sus datos durante los plazos de prescripci\u00f3n aplicables o seg\u00fan sea necesario para cumplir con una obligaci\u00f3n legal o reglamentaria.<\/p><p>El procesamiento de datos personales terminar\u00e1 en los siguientes casos: (i) cuando se haya alcanzado el prop\u00f3sito para el cual se recopilaron los datos y\/o los datos ya no sean necesarios o relevantes para cumplir con ese prop\u00f3sito; (ii) cuando el titular de los datos solicite la eliminaci\u00f3n de sus datos; y (iii) cuando haya una orden legal en ese sentido.<\/p><p>En caso de terminaci\u00f3n del procesamiento de datos personales, respetando los eventos previstos por la legislaci\u00f3n aplicable o esta Pol\u00edtica de Privacidad, los datos personales ser\u00e1n eliminados y esta Pol\u00edtica ya no ser\u00e1 aplicable a su relaci\u00f3n con MsB Manager, LLC.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e7ed07 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"2e7ed07\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">12. Cambios en la Pol\u00edtica de Privacidad\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c21b14 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"3c21b14\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Debido a la evoluci\u00f3n continua de su modelo de negocio, MsB Manager se reserva el derecho de cambiar esta pol\u00edtica de privacidad en cualquier momento, publicando la versi\u00f3n actualizada en su sitio web. Si hay un cambio significativo en el procesamiento de datos personales, se le informar\u00e1 por correo electr\u00f3nico y tendr\u00e1 la oportunidad de revisar la pol\u00edtica revisada antes de decidir continuar usando nuestros Servicios.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b15431 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"9b15431\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>Esta Pol\u00edtica fue actualizada el 27 de agosto de 2024.<\/em><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b648322 elementor-widget__width-initial jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"b648322\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si tiene alguna pregunta sobre esta Pol\u00edtica o sobre nuestras pr\u00e1cticas de privacidad, comun\u00edquese con nosotros en:<\/p><p>MsB Manager, LLC<br \/>345 W Sand Lake Rd, STE 210 Office 3368<br \/>Orlando, FL 32819 US<br \/><a href=\"http:\/\/www.msbmanager.us\" target=\"_new\" rel=\"noopener\">www.msbmanager.us<\/a><br \/><a rel=\"noopener\">contact@msbmanager.us<\/a><br \/>(617) 347-5256<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\r\n\t\t\t<div id=\"daexthefu-container\"\r\n\t\t\t\tclass=\"daexthefu-container daexthefu-layout-side-by-side daexthefu-alignment-left\"\r\n\t\t\t\tdata-post-id=\"926\">\r\n\r\n\t\t\t\t<div class=\"daexthefu-feedback\">\r\n\t\t\t\t\t<div class=\"daexthefu-text\">\r\n\t\t\t\t\t\t<h3 class=\"daexthefu-title\">Was this helpful?<\/h3>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"daexthefu-buttons-container\">\r\n\t\t\t\t\t\t<div class=\"daexthefu-buttons\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t<div class=\"daexthefu-yes daexthefu-button daexthefu-button-type-text\" data-value=\"1\">\r\n\t\t\t\t<div class=\"daexthefu-button-text\">Yes<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t<div class=\"daexthefu-no daexthefu-button daexthefu-button-type-text\" data-value=\"0\">\r\n\t\t\t\t<div class=\"daexthefu-button-text\">No<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"daexthefu-comment\">\r\n\t\t\t\t\t<div class=\"daexthefu-comment-top-container\">\r\n\t\t\t\t\t\t<label id=\"daexthefu-comment-label\" class=\"daexthefu-comment-label\"><\/label>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"daexthefu-comment-character-counter-container\">\r\n\t\t\t\t\t\t\t\t<div id=\"daexthefu-comment-character-counter-number\"\r\n\t\t\t\t\t\t\t\t\tclass=\"daexthefu-comment-character-counter-number\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"daexthefu-comment-character-counter-text\"><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<textarea id=\"daexthefu-comment-textarea\" class=\"daexthefu-comment-textarea\"\r\n\t\t\t\t\t\t\t\tplaceholder=\"Type your message\"\r\n\t\t\t\t\t\t\t\tmaxlength=\"\r\n\t\t\t\t\t\t\t\t400\t\t\t\t\t\t\t\t\t\"><\/textarea>\r\n\t\t\t\t\t<div class=\"daexthefu-comment-buttons-container\">\r\n\t\t\t\t\t\t<button class=\"daexthefu-comment-submit daexthefu-button\">Submit<\/button>\r\n\t\t\t\t\t\t<button class=\"daexthefu-comment-cancel daexthefu-button\">Cancel<\/button>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"daexthefu-successful-submission-text\">Thanks for your feedback!<\/div>\r\n\r\n\t\t\t<\/div>\r\n\r\n\t\t\t","protected":false},"excerpt":{"rendered":"<p>MSB Manager, LLC. Pol\u00edticas de Privacidad 1. Consideraciones Iniciales MsB Manager, LLC. (\u201cMsB Manager\u201d o \u201cnosotros\u201d) toma la privacidad muy en serio. Por ello, en esta Pol\u00edtica de Privacidad (\u201cPol\u00edtica\u201d) explicamos c\u00f3mo utilizamos, almacenamos, compartimos y protegemos los datos personales recopilados durante el uso de nuestros servicios y soluciones (en conjunto, los \u201cServicios\u201d) y visitas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_helpful_status":1,"footnotes":""},"class_list":["post-926","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/msbmanager.us\/es\/wp-json\/wp\/v2\/pages\/926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/msbmanager.us\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/msbmanager.us\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/msbmanager.us\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/msbmanager.us\/es\/wp-json\/wp\/v2\/comments?post=926"}],"version-history":[{"count":10,"href":"https:\/\/msbmanager.us\/es\/wp-json\/wp\/v2\/pages\/926\/revisions"}],"predecessor-version":[{"id":936,"href":"https:\/\/msbmanager.us\/es\/wp-json\/wp\/v2\/pages\/926\/revisions\/936"}],"wp:attachment":[{"href":"https:\/\/msbmanager.us\/es\/wp-json\/wp\/v2\/media?parent=926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}